{"id":7419,"date":"2026-01-15T10:19:47","date_gmt":"2026-01-15T09:19:47","guid":{"rendered":"https:\/\/reseau-amylose.org\/jesuissoignant\/?page_id=7419"},"modified":"2026-03-11T16:13:50","modified_gmt":"2026-03-11T15:13:50","slug":"test-genetique-patient-symptomatique-amylose","status":"publish","type":"page","link":"http:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/","title":{"rendered":"Faire un test g\u00e9n\u00e9tique chez un patient symptomatique (cas index)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7419\" class=\"elementor elementor-7419\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dbf0bf6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dbf0bf6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1dbf1c3\" data-id=\"1dbf1c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf75dfa elementor-widget elementor-widget-heading\" data-id=\"bf75dfa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Faire un test g\u00e9n\u00e9tique chez un patient symptomatique (cas index) avec amylose \u00e0 transthyr\u00e9tine<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b08d518 elementor-widget elementor-widget-heading\" data-id=\"b08d518\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Test g\u00e9n\u00e9tique dans l\u2019amylose : quand le prescrire chez un patient symptomatique ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2866a79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2866a79\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-978e980\" data-id=\"978e980\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eedfa59 elementor-widget elementor-widget-text-editor\" data-id=\"eedfa59\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"563\" data-end=\"772\">Le <strong data-start=\"566\" data-end=\"626\">test g\u00e9n\u00e9tique du g\u00e8ne de la transthyr\u00e9tine (TTR) chez un patient symptomatique<\/strong> est une analyse mol\u00e9culaire visant \u00e0 identifier une mutation amylo\u00efdog\u00e8ne responsable d\u2019une amylose h\u00e9r\u00e9ditaire li\u00e9e \u00e0 la transthyr\u00e9tine (ATTRv). L&rsquo;acronyme ATTRv est utilis\u00e9 pour l&rsquo;Amylose \u00e0 Transthyr\u00e9tine h\u00e9r\u00e9ditaire, le \u00ab\u00a0v\u00a0\u00bb est utilis\u00e9 pour variant g\u00e9n\u00e9tique, c&rsquo;est \u00e0 dire h\u00e9r\u00e9ditaire.<\/p><p data-start=\"782\" data-end=\"891\">Le test g\u00e9n\u00e9tique du g\u00e8ne <strong data-start=\"808\" data-end=\"815\">TTR<\/strong> permet d\u2019identifier une <strong data-start=\"840\" data-end=\"888\">amylose \u00e0 transthyr\u00e9tine h\u00e9r\u00e9ditaire (ATTRv)<\/strong>.<\/p><p data-start=\"898\" data-end=\"953\">Il peut \u00eatre r\u00e9alis\u00e9 dans deux situations diff\u00e9rentes :<\/p><ul><li data-start=\"898\" data-end=\"953\">chez un <strong data-start=\"966\" data-end=\"1023\">patient pr\u00e9sentant des sympt\u00f4mes \u00e9vocateurs d\u2019amylose<\/strong><\/li><li data-start=\"898\" data-end=\"953\">chez un <strong data-start=\"1036\" data-end=\"1100\">membre de la famille d\u2019un patient porteur d\u2019une mutation TTR<\/strong>.<\/li><\/ul><p data-start=\"1110\" data-end=\"1280\">Ces deux situations correspondent \u00e0 des d\u00e9marches m\u00e9dicales distinctes, notamment concernant <strong data-start=\"1203\" data-end=\"1279\">la prescription du test g\u00e9n\u00e9tique et l\u2019organisation du conseil g\u00e9n\u00e9tique<\/strong>.<\/p><p data-start=\"1110\" data-end=\"1280\">\u00a0<\/p><p data-start=\"774\" data-end=\"971\">Chez un patient pr\u00e9sentant des sympt\u00f4mes compatibles avec une atteinte neurologique, cardiaque, mixte ou syst\u00e9mique \u00e9vocatrice d\u2019amylose, ce test fait partie int\u00e9grante de la d\u00e9marche diagnostique.<\/p><p data-start=\"973\" data-end=\"1098\">Il permet de confirmer ou d\u2019exclure une ATTRv et conditionne l\u2019organisation de la prise en charge th\u00e9rapeutique et familiale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d831390 elementor-widget elementor-widget-heading\" data-id=\"d831390\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Indication du test g\u00e9n\u00e9tique chez le patient symptomatique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4575c3b elementor-widget elementor-widget-text-editor\" data-id=\"4575c3b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"1167\" data-end=\"1345\">Chez tout patient pr\u00e9sentant des manifestations compatibles avec une amylose h\u00e9r\u00e9ditaire li\u00e9e \u00e0 la transthyr\u00e9tine, la r\u00e9alisation d\u2019un test g\u00e9n\u00e9tique du g\u00e8ne TTR s\u2019int\u00e8gre dans :<\/p><ul><li data-start=\"1349\" data-end=\"1381\">la phase de suspicion clinique<\/li><li data-start=\"1349\" data-end=\"1381\">la confirmation \u00e9tiologique<\/li><li data-start=\"1349\" data-end=\"1381\">l\u2019orientation th\u00e9rapeutique<\/li><li data-start=\"1349\" data-end=\"1381\">l\u2019organisation du parcours familial<\/li><\/ul><p data-start=\"1487\" data-end=\"1591\">Tout m\u00e9decin est habilit\u00e9 \u00e0 prescrire cette analyse g\u00e9n\u00e9tique d\u00e8s lors que le patient est symptomatique.<\/p><p data-start=\"1593\" data-end=\"1746\">Il n\u2019est pas obligatoire d\u2019appartenir \u00e0 un centre expert pour prescrire le test.<br data-start=\"1673\" data-end=\"1676\" \/>Cependant, il est fortement recommand\u00e9 que la d\u00e9marche soit r\u00e9alis\u00e9e :<\/p><ul><li data-start=\"1750\" data-end=\"1806\">par un m\u00e9decin ayant une expertise dans l\u2019amylose<br data-start=\"1799\" data-end=\"1802\" \/>ou<\/li><li data-start=\"1750\" data-end=\"1806\">en coordination avec un centre expert du R\u00e9seau Amylose<br data-start=\"1864\" data-end=\"1867\" \/>ou<\/li><li data-start=\"1750\" data-end=\"1806\">en lien avec un centre de g\u00e9n\u00e9tique m\u00e9dicale<\/li><\/ul><p data-start=\"1922\" data-end=\"2030\">Cette organisation garantit une information adapt\u00e9e et une ma\u00eetrise des aspects pratiques et r\u00e9glementaires.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a35205 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a35205\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da2c7c5\" data-id=\"da2c7c5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1fcf53 elementor-widget elementor-widget-heading\" data-id=\"c1fcf53\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Test g\u00e9n\u00e9tique dans l\u2019amylose : patient symptomatique vs sujet apparent\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49db385 elementor-widget elementor-widget-text-editor\" data-id=\"49db385\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><table><thead><tr><th>Situation<\/th><th>Objectif du test<\/th><th>Qui peut prescrire<\/th><th>Organisation<\/th><th>Particularit\u00e9s<\/th><\/tr><\/thead><tbody><tr><td><strong>Patient symptomatique avec suspicion d\u2019amylose<\/strong><\/td><td>Confirmer le diagnostic et identifier une amylose ATTR h\u00e9r\u00e9ditaire<\/td><td>Cardiologue, neurologue ou sp\u00e9cialiste<\/td><td>Test r\u00e9alis\u00e9 dans le cadre du bilan diagnostique<\/td><td>Permet de distinguer ATTRv d\u2019ATTR sauvage<\/td><\/tr><tr><td><strong>Sujet asymptomatique apparent\u00e9 \u00e0 un patient porteur d\u2019une mutation TTR<\/strong><\/td><td>Identifier les porteurs de la mutation familiale<\/td><td><strong>M\u00e9decin g\u00e9n\u00e9ticien uniquement<\/strong><\/td><td>Parcours structur\u00e9 de conseil g\u00e9n\u00e9tique<\/td><td>D\u00e9marche volontaire encadr\u00e9e par la loi<\/td><\/tr><\/tbody><\/table><p>\u00a0<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b74c36c elementor-widget elementor-widget-heading\" data-id=\"b74c36c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Test g\u00e9n\u00e9tique chez un sujet sain : pourquoi un conseil g\u00e9n\u00e9tique ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39ddb2b elementor-widget elementor-widget-text-editor\" data-id=\"39ddb2b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"2410\" data-end=\"2566\">Lorsqu\u2019une mutation du g\u00e8ne de la transthyr\u00e9tine (<strong data-start=\"2438\" data-end=\"2445\">TTR)<\/strong> est identifi\u00e9e chez un patient atteint d\u2019une amylose ATTR h\u00e9r\u00e9ditaire, les membres de sa famille peuvent \u00eatre concern\u00e9s.<\/p><p data-start=\"2571\" data-end=\"2700\">La transmission est <strong data-start=\"2591\" data-end=\"2616\">autosomique dominante<\/strong> : chaque enfant d\u2019un patient porteur a <strong data-start=\"2656\" data-end=\"2699\">50 % de risque d\u2019h\u00e9riter de la mutation<\/strong>.<\/p><p data-start=\"2705\" data-end=\"2916\">Chez une personne sans sympt\u00f4me, le test g\u00e9n\u00e9tique est appel\u00e9 <strong data-start=\"2767\" data-end=\"2792\">test pr\u00e9symptomatique<\/strong>.<br data-start=\"2793\" data-end=\"2796\" \/>Sa r\u00e9alisation n\u00e9cessite une d\u00e9marche sp\u00e9cifique appel\u00e9e <strong data-start=\"2855\" data-end=\"2876\">conseil g\u00e9n\u00e9tique<\/strong>, r\u00e9alis\u00e9e dans des centres sp\u00e9cialis\u00e9s<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7f86faf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7f86faf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d009244\" data-id=\"d009244\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8e0ef6 elementor-widget elementor-widget-heading\" data-id=\"f8e0ef6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Organisation pr\u00e9alable au test g\u00e9n\u00e9tique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e56d166 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e56d166\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e5bd1aa\" data-id=\"e5bd1aa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e51b0b elementor-widget elementor-widget-heading\" data-id=\"9e51b0b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Information pr\u00e9-test et consentement<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d85caa9 elementor-widget elementor-widget-text-editor\" data-id=\"d85caa9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"2122\" data-end=\"2218\">Avant toute r\u00e9alisation, le patient doit \u00eatre inform\u00e9 de mani\u00e8re claire, loyale et adapt\u00e9e sur :<\/p><ul><li data-start=\"2222\" data-end=\"2264\">les objectifs diagnostiques de l\u2019analyse<\/li><li data-start=\"2222\" data-end=\"2264\">ses implications pronostiques et th\u00e9rapeutiques<\/li><li data-start=\"2222\" data-end=\"2264\">les cons\u00e9quences potentielles pour les apparent\u00e9s<\/li><li data-start=\"2222\" data-end=\"2264\">le caract\u00e8re h\u00e9r\u00e9ditaire et autosomique dominant de la maladie<\/li><\/ul><p data-start=\"2439\" data-end=\"2575\">Un consentement \u00e9clair\u00e9 \u00e9crit est indispensable avant le pr\u00e9l\u00e8vement, conform\u00e9ment \u00e0 la r\u00e9glementation en vigueur en g\u00e9n\u00e9tique m\u00e9dicale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e477a54\" data-id=\"e477a54\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bced50 elementor-widget elementor-widget-heading\" data-id=\"7bced50\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Arbre g\u00e9n\u00e9alogique : outil central<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82c7fc1 elementor-widget elementor-widget-text-editor\" data-id=\"82c7fc1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"2395\" data-end=\"2474\">L\u2019\u00e9tablissement d\u2019un arbre g\u00e9n\u00e9alogique sur au moins trois g\u00e9n\u00e9rations permet :<\/p><ul><li data-start=\"2478\" data-end=\"2519\">d\u2019identifier des cas familiaux suspects ou confirm\u00e9s d&rsquo;amylose<\/li><li data-start=\"2478\" data-end=\"2519\">de rep\u00e9rer des d\u00e9c\u00e8s inexpliqu\u00e9s compatibles<\/li><li data-start=\"2478\" data-end=\"2519\">d\u2019anticiper une strat\u00e9gie de d\u00e9pistage cibl\u00e9e<\/li><li data-start=\"2478\" data-end=\"2519\">d\u2019aider le patient \u00e0 comprendre la dimension familiale et leur relation g\u00e9n\u00e9tique et leur adresse personnelle afin de leur proposer si le test du cas index est positif un conseil g\u00e9n\u00e9tique. Le R\u00e9seau Amylose met \u00e0 disposition la liste des centres pour le conseil g\u00e9n\u00e9tique :\u00a0<b>cliquez ici pour acc\u00e9der \u00e0 la liste\u00a0<\/b><\/li><li>\u00a0<\/li><\/ul><p data-start=\"2620\" data-end=\"2708\">Un bloc-notes sp\u00e9cifique du R\u00e9seau Amylose est disponible pour faciliter cette d\u00e9marche. <em>VOIR CI-DESSOUS<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-39f478e\" data-id=\"39f478e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a7065b elementor-widget elementor-widget-heading\" data-id=\"0a7065b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Modalit\u00e9s techniques<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1634391 elementor-widget elementor-widget-text-editor\" data-id=\"1634391\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"3062\" data-end=\"3170\">Le test g\u00e9n\u00e9tique repose sur un pr\u00e9l\u00e8vement sanguin adress\u00e9 \u00e0 un laboratoire de g\u00e9n\u00e9tique mol\u00e9culaire agr\u00e9\u00e9.<\/p><p data-start=\"3172\" data-end=\"3265\">L\u2019analyse permet d\u2019identifier la pr\u00e9sence ou l\u2019absence d\u2019une variation pathog\u00e8ne du g\u00e8ne TTR.<\/p><p data-start=\"3267\" data-end=\"3363\">En cas de mutation identifi\u00e9e chez un patient symptomatique, le diagnostic d\u2019ATTRv est confirm\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bf70ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bf70ac\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-785c152\" data-id=\"785c152\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c33adc6 elementor-widget elementor-widget-heading\" data-id=\"c33adc6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les 3 \u00e9tapes du conseil g\u00e9n\u00e9tique dans l\u2019amylose ATTR<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7eb10e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7eb10e1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e4d3b5f\" data-id=\"e4d3b5f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1df100c elementor-widget elementor-widget-heading\" data-id=\"1df100c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1\ufe0f\u20e3 Consultation d\u2019information<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ec8e1c elementor-widget elementor-widget-text-editor\" data-id=\"2ec8e1c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li data-start=\"3123\" data-end=\"3166\">consultation avec un <strong data-start=\"3144\" data-end=\"3166\">m\u00e9decin g\u00e9n\u00e9ticien<\/strong><\/li><li data-start=\"3123\" data-end=\"3166\">\u00e9valuation avec un <strong data-start=\"3188\" data-end=\"3203\">cardiologue<\/strong><\/li><li data-start=\"3123\" data-end=\"3166\">entretien avec un <strong data-start=\"3224\" data-end=\"3239\">psychologue<\/strong><\/li><\/ul><p data-start=\"3241\" data-end=\"3320\">Objectif :<br data-start=\"3251\" data-end=\"3254\" \/>expliquer la maladie, la transmission et les implications du test.<\/p><p data-start=\"3322\" data-end=\"3424\">\u00c0 l\u2019issue de cette \u00e9tape, la personne peut <strong data-start=\"3365\" data-end=\"3423\">choisir librement de r\u00e9aliser ou non le test g\u00e9n\u00e9tique<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2de62eb\" data-id=\"2de62eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16a9ebf elementor-widget elementor-widget-heading\" data-id=\"16a9ebf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2\ufe0f\u20e3 R\u00e9alisation du test g\u00e9n\u00e9tique<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7271871 elementor-widget elementor-widget-text-editor\" data-id=\"7271871\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"3470\" data-end=\"3506\">Si la personne souhaite poursuivre :<\/p><ul><li data-start=\"3510\" data-end=\"3545\">r\u00e9alisation d\u2019une <strong data-start=\"3528\" data-end=\"3545\">prise de sang<\/strong><\/li><li data-start=\"3510\" data-end=\"3545\">prescription et encadrement par le <strong data-start=\"3583\" data-end=\"3597\">g\u00e9n\u00e9ticien<\/strong><\/li><li data-start=\"3510\" data-end=\"3545\">possibilit\u00e9 d\u2019accompagnement psychologique.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-eb913e7\" data-id=\"eb913e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8772de4 elementor-widget elementor-widget-heading\" data-id=\"8772de4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3\ufe0f\u20e3 Consultation d\u2019annonce des r\u00e9sultats<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a643f60 elementor-widget elementor-widget-text-editor\" data-id=\"a643f60\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"3696\" data-end=\"3756\">Les r\u00e9sultats sont expliqu\u00e9s lors d\u2019une consultation d\u00e9di\u00e9e.<\/p><p data-start=\"3758\" data-end=\"3775\">Deux situations :<\/p><ul><li data-start=\"3779\" data-end=\"3827\"><strong data-start=\"3779\" data-end=\"3802\">absence de mutation<\/strong> \u2192 aucun suivi sp\u00e9cifique<\/li><li data-start=\"3779\" data-end=\"3827\"><strong data-start=\"3830\" data-end=\"3854\">pr\u00e9sence de mutation<\/strong> \u2192 mise en place d\u2019un <strong data-start=\"3876\" data-end=\"3904\">suivi m\u00e9dical sp\u00e9cialis\u00e9<\/strong><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-90ea904 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"90ea904\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-cfe2793\" data-id=\"cfe2793\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4044e09 elementor-widget elementor-widget-heading\" data-id=\"4044e09\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les professionnels impliqu\u00e9s dans le conseil g\u00e9n\u00e9tique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a73733f elementor-widget elementor-widget-text-editor\" data-id=\"a73733f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><thead><tr><th>Professionnel<\/th><th>R\u00f4le<\/th><\/tr><\/thead><tbody><tr><td>G\u00e9n\u00e9ticien<\/td><td>information, prescription du test, interpr\u00e9tation<\/td><\/tr><tr><td>Cardiologue<\/td><td>\u00e9valuation clinique et organisation du suivi<\/td><\/tr><tr><td>Psychologue<\/td><td>accompagnement dans la d\u00e9cision et l\u2019annonce<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-341f266\" data-id=\"341f266\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b7c933d elementor-widget elementor-widget-image\" data-id=\"b7c933d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/03\/test-genetique-patient-symptomatique-cas-index-avec-amylose-transthyretine-683x1024.png\" class=\"attachment-large size-large wp-image-7838\" alt=\"test-ge\u0301ne\u0301tique-patient-symptomatique-cas-index-avec-amylose-transthyre\u0301tine\" srcset=\"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/03\/test-genetique-patient-symptomatique-cas-index-avec-amylose-transthyretine-683x1024.png 683w, http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/03\/test-genetique-patient-symptomatique-cas-index-avec-amylose-transthyretine-200x300.png 200w, http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/03\/test-genetique-patient-symptomatique-cas-index-avec-amylose-transthyretine-768x1152.png 768w, http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/03\/test-genetique-patient-symptomatique-cas-index-avec-amylose-transthyretine.png 1024w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-851bcfe elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"851bcfe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-395ebad\" data-id=\"395ebad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c24338 elementor-widget elementor-widget-heading\" data-id=\"6c24338\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rendu du test g\u00e9n\u00e9tique chez un patient symptomatique (cas index)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb958ed elementor-widget elementor-widget-text-editor\" data-id=\"eb958ed\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"3439\" data-end=\"3599\">Le rendu du test g\u00e9n\u00e9tique chez un patient suspect d\u2019amylose h\u00e9r\u00e9ditaire li\u00e9e \u00e0 la transthyr\u00e9tine constitue une <strong data-start=\"3551\" data-end=\"3598\">\u00e9tape m\u00e9dicale majeure du parcours de soins<\/strong>.<\/p><p data-start=\"3601\" data-end=\"3758\">Il ne s\u2019agit pas d\u2019une simple communication de r\u00e9sultat biologique, mais d\u2019un temps m\u00e9dical structur\u00e9, \u00e0 fort impact diagnostique, th\u00e9rapeutique et familial.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54a3f2b elementor-widget elementor-widget-heading\" data-id=\"54a3f2b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Cadre du rendu<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b443fe7 elementor-widget elementor-widget-text-editor\" data-id=\"b443fe7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"3784\" data-end=\"3812\">Le rendu doit \u00eatre r\u00e9alis\u00e9 :<\/p><ul><li data-start=\"3816\" data-end=\"3849\">dans un cadre m\u00e9dical appropri\u00e9<\/li><li data-start=\"3816\" data-end=\"3849\">par un m\u00e9decin form\u00e9 \u00e0 la pathologie ou en lien avec un centre expert<\/li><li data-start=\"3816\" data-end=\"3849\">lors d\u2019une consultation d\u00e9di\u00e9e<\/li><li data-start=\"3816\" data-end=\"3849\">en pr\u00e9sentiel<\/li><li data-start=\"3816\" data-end=\"3849\">avec un temps d\u2019\u00e9change suffisant<\/li><\/ul><p data-start=\"4016\" data-end=\"4037\">Le m\u00e9decin rappelle :<\/p><ul><li data-start=\"4041\" data-end=\"4092\">le contexte clinique ayant motiv\u00e9 la prescription<\/li><li data-start=\"4041\" data-end=\"4092\">les objectifs de l\u2019analyse g\u00e9n\u00e9tique<\/li><li data-start=\"4041\" data-end=\"4092\">les implications possibles du r\u00e9sultat<\/li><\/ul><p data-start=\"4178\" data-end=\"4256\">Le patient doit avoir \u00e9t\u00e9 inform\u00e9 en amont du cadre du rendu et de ses enjeux.<\/p><p data-start=\"4258\" data-end=\"4312\">S\u2019il le souhaite, il peut \u00eatre accompagn\u00e9 d\u2019un proche.<\/p><p data-start=\"4314\" data-end=\"4410\">La tra\u00e7abilit\u00e9 du rendu et des informations d\u00e9livr\u00e9es dans le dossier m\u00e9dical est indispensable.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47372ed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47372ed\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6bd2e0b\" data-id=\"6bd2e0b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95d9397 elementor-widget elementor-widget-heading\" data-id=\"95d9397\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">R\u00e9sultat du test g\u00e9n\u00e9tique n\u00e9gatif<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6b8697 elementor-widget elementor-widget-text-editor\" data-id=\"e6b8697\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"4458\" data-end=\"4540\">Un test est n\u00e9gatif lorsqu\u2019aucune mutation pathog\u00e8ne du g\u00e8ne TTR n\u2019est identifi\u00e9e.<\/p><p data-start=\"4542\" data-end=\"4576\">Il est essentiel d\u2019expliquer que :<\/p><ul><li data-start=\"4580\" data-end=\"4657\">ce r\u00e9sultat exclut une amylose h\u00e9r\u00e9ditaire li\u00e9e \u00e0 la transthyr\u00e9tine (ATTRv)<\/li><li data-start=\"4580\" data-end=\"4657\">il n\u2019exclut pas les autres formes d\u2019amylose<\/li><\/ul><p data-start=\"4707\" data-end=\"4718\">Notamment :<\/p><ul><li data-start=\"4722\" data-end=\"4751\">l\u2019amylose \u00e0 cha\u00eenes l\u00e9g\u00e8res<\/li><li data-start=\"4722\" data-end=\"4751\">l\u2019amylose \u00e0 transthyr\u00e9tine de type sauvage<\/li><\/ul><p data-start=\"4800\" data-end=\"4826\">Le m\u00e9decin doit pr\u00e9ciser :<\/p><ul><li data-start=\"4830\" data-end=\"4877\">la poursuite \u00e9ventuelle du bilan diagnostique<\/li><li data-start=\"4830\" data-end=\"4877\">les examens compl\u00e9mentaires envisag\u00e9s<\/li><li data-start=\"4830\" data-end=\"4877\">les hypoth\u00e8ses diagnostiques restantes<\/li><\/ul><p data-start=\"4964\" data-end=\"5065\">Ce temps d\u2019explication est essentiel pour \u00e9viter toute incompr\u00e9hension ou faux sentiment de s\u00e9curit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-45d775f\" data-id=\"45d775f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d03b60 elementor-widget elementor-widget-heading\" data-id=\"5d03b60\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">R\u00e9sultat du test g\u00e9n\u00e9tique positif<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c33da95 elementor-widget elementor-widget-text-editor\" data-id=\"c33da95\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"5113\" data-end=\"5190\">Un test est positif lorsqu\u2019une mutation pathog\u00e8ne du g\u00e8ne TTR est identifi\u00e9e.<\/p><p data-start=\"5192\" data-end=\"5306\">Chez un patient symptomatique, cela confirme le diagnostic d\u2019amylose h\u00e9r\u00e9ditaire li\u00e9e \u00e0 la transthyr\u00e9tine (ATTRv).<\/p><p data-start=\"5308\" data-end=\"5394\">L\u2019annonce doit \u00eatre structur\u00e9e, progressive et peut \u00eatre envisag\u00e9e en plusieurs temps.<\/p><h4 data-start=\"3607\" data-end=\"3636\">1\ufe0f\u20e3 Temps g\u00e9n\u00e9tique<\/h4><p data-start=\"5425\" data-end=\"5446\">Le m\u00e9decin explique :<\/p><ul><li data-start=\"5450\" data-end=\"5485\">la nature g\u00e9n\u00e9tique de la maladie<\/li><li data-start=\"5450\" data-end=\"5485\">la transmission autosomique dominante<\/li><li data-start=\"5450\" data-end=\"5485\">la variabilit\u00e9 d\u2019expression clinique<\/li><li data-start=\"5450\" data-end=\"5485\">le fait qu\u2019un portage g\u00e9n\u00e9tique n\u2019entra\u00eene pas syst\u00e9matiquement une atteinte identique chez tous les porteurs<\/li><\/ul><p data-start=\"5684\" data-end=\"5764\">Les explications sont adapt\u00e9es \u00e0 la mutation identifi\u00e9e et au contexte clinique.<\/p><h4 data-start=\"3789\" data-end=\"3819\">2\ufe0f\u20e3 Temps m\u00e9dical<\/h4><p data-start=\"5793\" data-end=\"5838\">Le rendu s\u2019accompagne d\u2019une explication sur :<\/p><ul><li data-start=\"5842\" data-end=\"5876\">la prise en charge th\u00e9rapeutique<\/li><li data-start=\"5842\" data-end=\"5876\">le suivi sp\u00e9cialis\u00e9<\/li><li data-start=\"5842\" data-end=\"5876\">l\u2019\u00e9valuation de l\u2019atteinte des diff\u00e9rents organes<\/li><\/ul><p data-start=\"5956\" data-end=\"6041\">Le lien entre le r\u00e9sultat g\u00e9n\u00e9tique et les sympt\u00f4mes pr\u00e9sent\u00e9s est clairement \u00e9tabli.<\/p><h4 data-start=\"3943\" data-end=\"3974\">3\ufe0f\u20e3 Temps familiale<\/h4><p data-start=\"6071\" data-end=\"6140\">Un \u00e9change sp\u00e9cifique doit \u00eatre consacr\u00e9 aux implications familiales.<\/p><p data-start=\"6142\" data-end=\"6166\">Le patient est inform\u00e9 :<\/p><ul><li data-start=\"6170\" data-end=\"6242\">de la possibilit\u00e9 d\u2019un d\u00e9pistage g\u00e9n\u00e9tique chez les apparent\u00e9s adultes<\/li><li data-start=\"6170\" data-end=\"6242\">du caract\u00e8re volontaire et encadr\u00e9 de la d\u00e9marche<\/li><li data-start=\"6170\" data-end=\"6242\">de la n\u00e9cessit\u00e9 d\u2019un conseil g\u00e9n\u00e9tique<\/li><\/ul><p data-start=\"6341\" data-end=\"6409\">L\u2019information des apparent\u00e9s rel\u00e8ve de la responsabilit\u00e9 du patient.<\/p><p data-start=\"6411\" data-end=\"6548\">S\u2019il ne souhaite pas informer directement ses proches, il peut confier cette mission \u00e0 l\u2019\u00e9quipe m\u00e9dicale, dans le respect du cadre l\u00e9gal.<\/p><p data-start=\"6550\" data-end=\"6639\">Un accompagnement peut \u00eatre propos\u00e9 pour l\u2019aider \u00e0 expliquer son diagnostic \u00e0 sa famille<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3301706 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3301706\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b10ab37\" data-id=\"b10ab37\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e77eb39 elementor-widget elementor-widget-heading\" data-id=\"e77eb39\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Commandez le bloc note pour r\u00e9aliser vos arbres g\u00e9n\u00e9alogiques<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d58262 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d58262\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78520a6\" data-id=\"78520a6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f20fece elementor-widget elementor-widget-image\" data-id=\"f20fece\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"543\" src=\"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2025\/03\/Arbre-genealogique-reseau-amylose-bloc-notes-768x543.png\" class=\"attachment-medium_large size-medium_large wp-image-7231\" alt=\"Arbre-ge\u0301ne\u0301alogique-reseau-amylose-bloc-notes\" srcset=\"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2025\/03\/Arbre-genealogique-reseau-amylose-bloc-notes-768x543.png 768w, http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2025\/03\/Arbre-genealogique-reseau-amylose-bloc-notes-300x212.png 300w, http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2025\/03\/Arbre-genealogique-reseau-amylose-bloc-notes-1024x723.png 1024w, http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2025\/03\/Arbre-genealogique-reseau-amylose-bloc-notes-1536x1085.png 1536w, http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2025\/03\/Arbre-genealogique-reseau-amylose-bloc-notes.png 1928w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6cab59e\" data-id=\"6cab59e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eba5799 elementor-widget elementor-widget-text-editor\" data-id=\"eba5799\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-854f28c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"854f28c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/reseau-amylose.org\/jesuissoignant\/bloc-notes-pour-la-prise-en-charge-de-lamylose\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cliquez ici<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11aefea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11aefea\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42753cd\" data-id=\"42753cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-670a8a6 elementor-widget elementor-widget-heading\" data-id=\"670a8a6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Test diagnostique vs test pr\u00e9dictif : distinction essentielle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b61769f elementor-widget elementor-widget-text-editor\" data-id=\"b61769f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dans l\u2019amylose h\u00e9r\u00e9ditaire li\u00e9e \u00e0 la transthyr\u00e9tine (ATTRv), il est essentiel de distinguer\u00a0<strong>deux types de tests g\u00e9n\u00e9tiques du g\u00e8ne TTR<\/strong>\u00a0: le\u00a0<strong>test diagnostique<\/strong>, r\u00e9alis\u00e9 chez un patient symptomatique, et le\u00a0<strong>test g\u00e9n\u00e9tique pr\u00e9dictif<\/strong>, propos\u00e9 aux apparent\u00e9s asymptomatiques d\u2019un cas index porteur d\u2019une mutation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2b971e elementor-widget elementor-widget-heading\" data-id=\"d2b971e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Test g\u00e9n\u00e9tique diagnostique chez un patient symptomatique\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-638d9c2 elementor-widget elementor-widget-text-editor\" data-id=\"638d9c2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le\u00a0<strong>test g\u00e9n\u00e9tique du g\u00e8ne TTR<\/strong>\u00a0est prescrit dans une d\u00e9marche diagnostique chez un patient pr\u00e9sentant des signes cliniques \u00e9vocateurs d\u2019amylose, notamment :<\/p><ul><li>neuropathie p\u00e9riph\u00e9rique progressive<\/li><li>cardiomyopathie infiltrative ou hypertrophique inexpliqu\u00e9e<\/li><li>syndrome du canal carpien bilat\u00e9ral<\/li><li>dysautonomie<\/li><li>atteinte syst\u00e9mique compatible avec une amylose<\/li><\/ul><p>Ce test permet\u00a0<strong>de confirmer ou d\u2019exclure une amylose h\u00e9r\u00e9ditaire li\u00e9e \u00e0 la transthyr\u00e9tine (ATTRv)<\/strong>.<\/p><p>Chez un patient symptomatique :<\/p><ul><li>le test peut \u00eatre\u00a0<strong>prescrit par tout m\u00e9decin<\/strong><\/li><li>il s\u2019inscrit dans la\u00a0<strong>d\u00e9marche diagnostique<\/strong><\/li><li>il n\u00e9cessite une\u00a0<strong>information pr\u00e9-test et un consentement \u00e9crit<\/strong><\/li><li>le r\u00e9sultat oriente\u00a0<strong>la prise en charge th\u00e9rapeutique et le suivi sp\u00e9cialis\u00e9<\/strong><\/li><\/ul><p>Un r\u00e9sultat positif confirme le diagnostic d\u2019ATTRv et implique l\u2019organisation d\u2019un\u00a0<strong>conseil g\u00e9n\u00e9tique familial<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d6f807 elementor-widget elementor-widget-heading\" data-id=\"5d6f807\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Test g\u00e9n\u00e9tique pr\u00e9dictif chez un apparent\u00e9 asymptomatique<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ffe023 elementor-widget elementor-widget-text-editor\" data-id=\"2ffe023\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le\u00a0<strong>test g\u00e9n\u00e9tique pr\u00e9dictif<\/strong>\u00a0est propos\u00e9 \u00e0 un\u00a0<strong>apparent\u00e9 adulte asymptomatique<\/strong>\u00a0d\u2019un patient porteur d\u2019une mutation amylo\u00efdog\u00e8ne du g\u00e8ne TTR.<\/p><p>L\u2019objectif n\u2019est pas de poser un diagnostic, mais de d\u00e9terminer si l\u2019apparent\u00e9 est\u00a0<strong>porteur de la mutation familiale<\/strong>, afin d\u2019organiser une surveillance m\u00e9dicale adapt\u00e9e.<\/p><p>Contrairement au test diagnostique, le test pr\u00e9dictif :<\/p><ul><li>s\u2019inscrit dans une\u00a0<strong>d\u00e9marche volontaire de m\u00e9decine pr\u00e9ventive<\/strong><\/li><li>n\u00e9cessite un\u00a0<strong>parcours de conseil g\u00e9n\u00e9tique structur\u00e9<\/strong><\/li><li>est prescrit\u00a0<strong>par un m\u00e9decin g\u00e9n\u00e9ticien<\/strong><\/li><li>comprend\u00a0<strong>plusieurs consultations et un temps de r\u00e9flexion<\/strong><\/li><\/ul><p>Le parcours implique g\u00e9n\u00e9ralement une\u00a0<strong>\u00e9quipe pluridisciplinaire<\/strong>, pouvant inclure :<\/p><ul><li>un\u00a0<strong>m\u00e9decin g\u00e9n\u00e9ticien<\/strong><\/li><li>un\u00a0<strong>conseiller en g\u00e9n\u00e9tique<\/strong><\/li><li>un\u00a0<strong>cardiologue sp\u00e9cialis\u00e9 dans l\u2019amylose<\/strong><\/li><li>un\u00a0<strong>psychologue<\/strong><\/li><\/ul><p>Ce cadre permet de garantir une information claire sur :<\/p><ul><li>la\u00a0<strong>transmission autosomique dominante<\/strong><\/li><li>les\u00a0<strong>implications psychologiques et familiales<\/strong><\/li><li>le\u00a0<strong>droit de ne pas savoir<\/strong><\/li><\/ul><p>Le test pr\u00e9dictif\u00a0<strong>n\u2019est pas propos\u00e9 aux mineurs<\/strong>, sauf b\u00e9n\u00e9fice m\u00e9dical imm\u00e9diat.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5599954 elementor-widget elementor-widget-text-editor\" data-id=\"5599954\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"gs\"><div class=\"\"><div id=\":cnd\" class=\"ii gt adO\"><div id=\":cne\" class=\"a3s aiL\"><div id=\"avWBGd-15387\"><div dir=\"ltr\"><div><div><table><thead><tr><th>Caract\u00e9ristique<\/th><th><strong>Test g\u00e9n\u00e9tique diagnostique<\/strong><\/th><th><strong>Test g\u00e9n\u00e9tique pr\u00e9dictif<\/strong><\/th><\/tr><\/thead><tbody><tr><td><strong>Personne concern\u00e9e<\/strong><\/td><td>Patient\u00a0<strong>symptomatique<\/strong>\u00a0suspect d\u2019amylose ATTRv<\/td><td><strong>Apparent\u00e9 asymptomatique<\/strong>\u00a0d\u2019un cas index porteur d\u2019une mutation TTR<\/td><\/tr><tr><td><strong>Objectif du test<\/strong><\/td><td><strong>Confirmer ou exclure le diagnostic<\/strong>\u00a0d\u2019ATTRv<\/td><td><strong>D\u00e9terminer si l\u2019apparent\u00e9 est porteur<\/strong>\u00a0de la mutation familiale<\/td><\/tr><tr><td><strong>Contexte m\u00e9dical<\/strong><\/td><td>D\u00e9marche\u00a0<strong>diagnostique<\/strong>\u00a0devant des sympt\u00f4mes \u00e9vocateurs<\/td><td>D\u00e9marche\u00a0<strong>pr\u00e9ventive et anticipative<\/strong>\u00a0chez un sujet sain<\/td><\/tr><tr><td><strong>Prescription<\/strong><\/td><td>Peut \u00eatre prescrite par\u00a0<strong>tout m\u00e9decin<\/strong><\/td><td>Prescription\u00a0<strong>encadr\u00e9e par un m\u00e9decin g\u00e9n\u00e9ticien<\/strong><\/td><\/tr><tr><td><strong>Cadre de r\u00e9alisation<\/strong><\/td><td>Parcours diagnostique habituel<\/td><td><strong>Parcours de conseil g\u00e9n\u00e9tique structur\u00e9<\/strong><\/td><\/tr><tr><td><strong>Professionnels impliqu\u00e9s<\/strong><\/td><td>M\u00e9decin prescripteur (souvent sp\u00e9cialiste ou centre expert)<\/td><td>\u00c9quipe pluridisciplinaire : g\u00e9n\u00e9ticien, conseiller en g\u00e9n\u00e9tique, cardiologue, psychologue<\/td><\/tr><tr><td><strong>Consultation d\u2019information pr\u00e9alable<\/strong><\/td><td>Information m\u00e9dicale et\u00a0<strong>consentement \u00e9crit<\/strong>\u00a0obligatoires<\/td><td><strong>Consultations de conseil g\u00e9n\u00e9tique<\/strong>\u00a0avec information approfondie<\/td><\/tr><tr><td><strong>Temps de r\u00e9flexion<\/strong><\/td><td>Non requis formellement<\/td><td><strong>Temps de r\u00e9flexion obligatoire<\/strong>\u00a0entre les consultations<\/td><\/tr><tr><td><strong>Population concern\u00e9e<\/strong><\/td><td>Patient pr\u00e9sentant des\u00a0<strong>manifestations cliniques compatibles<\/strong><\/td><td><strong>Apparent\u00e9s adultes uniquement<\/strong><\/td><\/tr><tr><td><strong>Mineurs<\/strong><\/td><td>Possible si indication clinique<\/td><td><strong>Non recommand\u00e9<\/strong>\u00a0en l\u2019absence de b\u00e9n\u00e9fice m\u00e9dical imm\u00e9diat<\/td><\/tr><tr><td><strong>Impact du r\u00e9sultat<\/strong><\/td><td>Confirme ou exclut le diagnostic et\u00a0<strong>oriente la prise en charge th\u00e9rapeutique<\/strong><\/td><td>Permet d\u2019identifier les\u00a0<strong>porteurs \u00e0 risque<\/strong>\u00a0et d\u2019organiser un\u00a0<strong>suivi pr\u00e9coce<\/strong><\/td><\/tr><tr><td><strong>Cons\u00e9quences familiales<\/strong><\/td><td>D\u00e9clenche la\u00a0<strong>proposition d\u2019un d\u00e9pistage familial<\/strong><\/td><td>Permet d\u2019identifier les\u00a0<strong>apparent\u00e9s porteurs ou non porteurs<\/strong><\/td><\/tr><tr><td><strong>Annonce du r\u00e9sultat<\/strong><\/td><td>Consultation m\u00e9dicale d\u00e9di\u00e9e<\/td><td>Consultation de restitution dans le cadre du\u00a0<strong>conseil g\u00e9n\u00e9tique<\/strong><\/td><\/tr><\/tbody><\/table><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"avWBGd-15388\" class=\"WhmR8e\" data-hash=\"0\">\u00a0<\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ad6fc3 elementor-widget elementor-widget-heading\" data-id=\"4ad6fc3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pourquoi cette distinction est essentielle ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3943e49 elementor-widget elementor-widget-text-editor\" data-id=\"3943e49\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La distinction entre\u00a0<strong>test diagnostique et test g\u00e9n\u00e9tique pr\u00e9dictif<\/strong>\u00a0est fondamentale en g\u00e9n\u00e9tique m\u00e9dicale, car elle r\u00e9pond \u00e0\u00a0<strong>deux questions diff\u00e9rentes<\/strong>\u00a0:<\/p><ul><li><strong>Le patient est-il atteint d\u2019une amylose ATTRv ?<\/strong>\u00a0\u2192 test diagnostique<\/li><li><strong>L\u2019apparent\u00e9 est-il porteur de la mutation familiale ?<\/strong>\u00a0\u2192 test pr\u00e9dictif<\/li><\/ul><p>Cette distinction conditionne :<\/p><ul><li><strong>le cadre l\u00e9gal de prescription<\/strong><\/li><li><strong>l\u2019organisation du conseil g\u00e9n\u00e9tique<\/strong><\/li><li><strong>l\u2019accompagnement psychologique et familial<\/strong><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4164d8 elementor-widget elementor-widget-heading\" data-id=\"e4164d8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00c0 retenir pour les m\u00e9decins<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ea1eb1 elementor-widget elementor-widget-text-editor\" data-id=\"0ea1eb1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Le\u00a0<strong>test g\u00e9n\u00e9tique TTR diagnostique<\/strong>\u00a0peut \u00eatre prescrit par tout m\u00e9decin chez un patient symptomatique.<\/li><li>Il n\u00e9cessite\u00a0<strong>une information pr\u00e9-test et un consentement \u00e9crit<\/strong>.<\/li><li>Le\u00a0<strong>test g\u00e9n\u00e9tique pr\u00e9dictif<\/strong>\u00a0chez un apparent\u00e9 asymptomatique est\u00a0<strong>strictement encadr\u00e9 par le conseil g\u00e9n\u00e9tique<\/strong>.<\/li><li>Il est prescrit\u00a0<strong>par un g\u00e9n\u00e9ticien dans un parcours multidisciplinaire<\/strong>.<\/li><li>Cette d\u00e9marche permet d\u2019organiser\u00a0<strong>un d\u00e9pistage familial et un suivi pr\u00e9coce des porteurs<\/strong>.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b113aa8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b113aa8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6e61c93\" data-id=\"6e61c93\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e87adc0 elementor-widget elementor-widget-heading\" data-id=\"e87adc0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00e9l\u00e9chargez ce document \u00e0 distribuer \u00e0 vos patients : <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a842ab elementor-widget elementor-widget-image\" data-id=\"3a842ab\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/01\/Triptyque-CAS-INDEX-Conseil-genetique-2024-TD2-08_12_2024-SO-1.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"486\" src=\"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/01\/annonce-genetique-apparente.jpg\" class=\"attachment-large size-large wp-image-7460\" alt=\"faire-un test-genetique-chez-un-apparente-reseau-amylose\" srcset=\"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/01\/annonce-genetique-apparente.jpg 700w, http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/01\/annonce-genetique-apparente-300x208.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-db8c28f\" data-id=\"db8c28f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1a2610 elementor-widget elementor-widget-text-editor\" data-id=\"e1a2610\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>\u00a0<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec730de elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ec730de\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-apparente-amylose\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tout savoir sur le test g\u00e9n\u00e9tique chez un apparent\u00e9<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-754120f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"754120f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c1abbb\" data-id=\"6c1abbb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ef1bd2 elementor-widget elementor-widget-heading\" data-id=\"3ef1bd2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conseil g\u00e9n\u00e9tique dans l\u2019amylose ATTRv<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d669262 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d669262\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0d241a7\" data-id=\"0d241a7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f104da8 elementor-widget elementor-widget-text-editor\" data-id=\"f104da8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"7156\" data-end=\"7253\">Le conseil g\u00e9n\u00e9tique occupe une place centrale dans la prise en charge des amyloses h\u00e9r\u00e9ditaires.<\/p><p data-start=\"7255\" data-end=\"7269\">Il s\u2019adresse :<\/p><ul><li data-start=\"7273\" data-end=\"7301\">aux patients diagnostiqu\u00e9s<\/li><li data-start=\"7273\" data-end=\"7301\">aux apparent\u00e9s adultes asymptomatiques<\/li><\/ul><p data-start=\"7346\" data-end=\"7357\">Il permet :<\/p><ul><li data-start=\"7361\" data-end=\"7412\">d\u2019expliquer la transmission autosomique dominante<\/li><li data-start=\"7361\" data-end=\"7412\">de pr\u00e9ciser le risque familial<\/li><li data-start=\"7361\" data-end=\"7412\">d\u2019\u00e9viter les interpr\u00e9tations erron\u00e9es<\/li><li data-start=\"7361\" data-end=\"7412\">de garantir une information encadr\u00e9e sur le plan \u00e9thique et l\u00e9gal<\/li><\/ul><p data-start=\"7561\" data-end=\"7631\">Il s\u2019inscrit dans une d\u00e9marche de m\u00e9decine pr\u00e9ventive et anticipative.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-35a655f\" data-id=\"35a655f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5005be elementor-widget elementor-widget-heading\" data-id=\"b5005be\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">D\u00e9roulement du conseil g\u00e9n\u00e9tique<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20dbc2c elementor-widget elementor-widget-text-editor\" data-id=\"20dbc2c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol data-start=\"7674\" data-end=\"7914\"><li data-start=\"7674\" data-end=\"7705\"><p data-start=\"7677\" data-end=\"7705\">Consultation d\u2019information<\/p><\/li><li data-start=\"7706\" data-end=\"7757\"><p data-start=\"7709\" data-end=\"7757\">Recueil de l\u2019histoire personnelle et familiale<\/p><\/li><li data-start=\"7758\" data-end=\"7801\"><p data-start=\"7761\" data-end=\"7801\">Discussion des motivations et attentes<\/p><\/li><li data-start=\"7802\" data-end=\"7825\"><p data-start=\"7805\" data-end=\"7825\">Temps de r\u00e9flexion<\/p><\/li><li data-start=\"7826\" data-end=\"7874\"><p data-start=\"7829\" data-end=\"7874\">Prescription encadr\u00e9e si d\u00e9cision favorable<\/p><\/li><li data-start=\"7875\" data-end=\"7914\"><p data-start=\"7878\" data-end=\"7914\">Restitution en consultation d\u00e9di\u00e9e<\/p><\/li><\/ol><p data-start=\"7916\" data-end=\"7959\">Le test g\u00e9n\u00e9tique n\u2019est jamais obligatoire.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58bc25f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58bc25f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ac6044\" data-id=\"7ac6044\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59f93ce elementor-widget elementor-widget-heading\" data-id=\"59f93ce\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aspects \u00e9thiques, psychologiques et l\u00e9gaux<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1289d8 elementor-widget elementor-widget-text-editor\" data-id=\"e1289d8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"8012\" data-end=\"8050\">La d\u00e9marche est strictement encadr\u00e9e :<\/p><ul><li data-start=\"8054\" data-end=\"8085\">consentement libre et \u00e9clair\u00e9<\/li><li data-start=\"8054\" data-end=\"8085\">confidentialit\u00e9 des donn\u00e9es<\/li><li data-start=\"8054\" data-end=\"8085\">droit de ne pas savoir<\/li><li data-start=\"8054\" data-end=\"8085\">information indirecte des apparent\u00e9s<\/li><\/ul><p data-start=\"8187\" data-end=\"8264\">L\u2019annonce d\u2019un risque g\u00e9n\u00e9tique peut avoir un impact psychologique important.<\/p><p data-start=\"8266\" data-end=\"8309\">Un accompagnement adapt\u00e9 peut \u00eatre propos\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21deeaf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21deeaf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eb820c4\" data-id=\"eb820c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6900311 elementor-widget elementor-widget-heading\" data-id=\"6900311\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Documents et ressources pour votre pratique\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6069b7 elementor-widget elementor-widget-heading\" data-id=\"c6069b7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">T\u00e9l\u00e9chargez nos documents <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a1be8fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a1be8fc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e43dc2a\" data-id=\"e43dc2a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09c483e elementor-widget elementor-widget-image\" data-id=\"09c483e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.reseau-amylose.org\/docuser\/storage\/sites\/13\/2020\/09\/TRIPTYQUE-Conseil-ge%CC%81ne%CC%81tique-Sept2020.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"486\" src=\"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/01\/conseil-genetique.jpg\" class=\"attachment-large size-large wp-image-7451\" alt=\"faire-un-test-genetique-chez-un-patient-symptomatique-conseil\" srcset=\"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/01\/conseil-genetique.jpg 650w, http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/01\/conseil-genetique-300x224.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2a1fa66\" data-id=\"2a1fa66\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f81a94d elementor-widget elementor-widget-image\" data-id=\"f81a94d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/reseau-amylose.org\/docuser\/storage\/sites\/5\/2022\/05\/TRIPTYQUE-National-AHC-Val30Met-pour-le-Cardiologue-Fev2021.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"486\" src=\"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/01\/Val30Met.jpg\" class=\"attachment-large size-large wp-image-7444\" alt=\"Faire-un-test-genetique-chez-un-patient-symptomatique-Val30Met\" srcset=\"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/01\/Val30Met.jpg 650w, http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/01\/Val30Met-300x224.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ea58c2b\" data-id=\"ea58c2b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c89f010 elementor-widget elementor-widget-image\" data-id=\"c89f010\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/reseau-amylose.org\/docuser\/storage\/sites\/5\/2022\/05\/TRIPTYQUE-National-AHC-Val122Ile-pour-le-Cardiologue-Fev2021.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"486\" src=\"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/01\/Val122.jpg\" class=\"attachment-large size-large wp-image-7443\" alt=\"Faire-un-test-genetique-chez-un-patient-symptomatique-Val122Ile\" srcset=\"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/01\/Val122.jpg 650w, http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/01\/Val122-300x224.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9cdbf95 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9cdbf95\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a5c9b82\" data-id=\"a5c9b82\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-435a217 elementor-widget elementor-widget-text-editor\" data-id=\"435a217\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les patients et les familles peuvent \u00eatre orient\u00e9s vers les centres de g\u00e9n\u00e9tique m\u00e9dicale, les centres experts du r\u00e9seau amylose et les ressources mises \u00e0 disposition par le R\u00e9seau Amylose. Ces structures permettent d\u2019assurer une prise en charge coordonn\u00e9e, coh\u00e9rente et adapt\u00e9e \u00e0 chaque situation.<\/p><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8047229 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8047229\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b266b9d\" data-id=\"b266b9d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3938cf3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3938cf3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/reseau-amylose.org\/jesuissoignant\/trouver-un-centre-de-genetique\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Trouver un centre de g\u00e9n\u00e9tique<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8903efe\" data-id=\"8903efe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aee1b8a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"aee1b8a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/reseau-amylose.org\/soins\/reseau-amylose-national\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Trouver un centre expert de l'amylose<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a386f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9a386f7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-00d8411\" data-id=\"00d8411\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d387a52 elementor-widget elementor-widget-heading\" data-id=\"d387a52\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Mod\u00e8le de lettre d\u2019information familiale (\u00e0 adapter)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fa2ae8 elementor-widget elementor-widget-text-editor\" data-id=\"7fa2ae8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"8689\" data-end=\"8776\">Un mod\u00e8le de lettre est mis \u00e0 disposition pour aider le patient \u00e0 informer ses proches.<\/p><p data-start=\"8778\" data-end=\"8817\">Cette lettre personnalisable explique :<\/p><ul><li data-start=\"8821\" data-end=\"8844\">le diagnostic d\u2019ATTRv<\/li><li data-start=\"8821\" data-end=\"8844\">le principe du conseil g\u00e9n\u00e9tique<\/li><li data-start=\"8821\" data-end=\"8844\">la proc\u00e9dure propos\u00e9e<\/li><li data-start=\"8821\" data-end=\"8844\">les coordonn\u00e9es utiles<\/li><\/ul><p data-start=\"8936\" data-end=\"8995\">Elle doit \u00eatre adapt\u00e9e \u00e0 la situation familiale du patient.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aef95c4 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"aef95c4\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/03\/lettre-cas-index-a-adapter.docx\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">T\u00e9l\u00e9chargez la lettre ICI<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2717ee4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2717ee4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac8ec9d\" data-id=\"ac8ec9d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eed558d elementor-widget elementor-widget-heading\" data-id=\"eed558d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Points cl\u00e9s pour les professionnels de sant\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-377cabe elementor-widget elementor-widget-text-editor\" data-id=\"377cabe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li data-start=\"9052\" data-end=\"9121\">Le test g\u00e9n\u00e9tique TTR est central dans la confirmation d\u2019une ATTRv.<\/li><li data-start=\"9052\" data-end=\"9121\">Le consentement \u00e9crit est obligatoire.<\/li><li data-start=\"9052\" data-end=\"9121\">Le rendu doit \u00eatre r\u00e9alis\u00e9 en consultation d\u00e9di\u00e9e.<\/li><li data-start=\"9052\" data-end=\"9121\">Un test n\u00e9gatif n\u2019exclut pas les autres amyloses.<\/li><li data-start=\"9052\" data-end=\"9121\">Un test positif impose une organisation th\u00e9rapeutique et un conseil g\u00e9n\u00e9tique familial.<\/li><li data-start=\"9052\" data-end=\"9121\">La prise en charge doit \u00eatre coordonn\u00e9e avec un centre expert du R\u00e9seau Amylose.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-331aa21 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"331aa21\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d4366dd\" data-id=\"d4366dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-136046d elementor-widget elementor-widget-heading\" data-id=\"136046d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ \u2013 Questions fr\u00e9quentes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f73b9ba elementor-widget elementor-widget-heading\" data-id=\"f73b9ba\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Qui peut prescrire un test g\u00e9n\u00e9tique TTR ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-137c469 elementor-widget elementor-widget-text-editor\" data-id=\"137c469\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chez un patient symptomatique, il peut \u00eatre prescrit par un sp\u00e9cialiste.<br data-start=\"4813\" data-end=\"4816\" \/>Chez un sujet asymptomatique, il doit \u00eatre prescrit <strong data-start=\"4868\" data-end=\"4926\">par un g\u00e9n\u00e9ticien dans le cadre d\u2019un conseil g\u00e9n\u00e9tique<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae51499 elementor-widget elementor-widget-heading\" data-id=\"ae51499\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Un test n\u00e9gatif exclut-il toute amylose ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86d1230 elementor-widget elementor-widget-text-editor\" data-id=\"86d1230\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"9643\" data-end=\"9703\">Non, il exclut l\u2019ATTRv mais pas les autres formes d\u2019amylose.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a55a895 elementor-widget elementor-widget-heading\" data-id=\"a55a895\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comment annoncer un r\u00e9sultat positif ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc47d4e elementor-widget elementor-widget-text-editor\" data-id=\"fc47d4e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"9748\" data-end=\"9817\">En consultation d\u00e9di\u00e9e, de mani\u00e8re structur\u00e9e, progressive et trac\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f8e8e2 elementor-widget elementor-widget-heading\" data-id=\"5f8e8e2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00c0 quels apparent\u00e9s proposer un test pr\u00e9dictif ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bddd1a1 elementor-widget elementor-widget-text-editor\" data-id=\"bddd1a1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"9871\" data-end=\"9948\">Aux apparent\u00e9s adultes <strong data-start=\"5174\" data-end=\"5205\">au premier degr\u00e9<\/strong> asymptomatiques d\u2019un cas index porteur d\u2019une mutation (parents, fr\u00e8res, s\u0153urs et enfants).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55c513b elementor-widget elementor-widget-heading\" data-id=\"55c513b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Le test pr\u00e9dictif est-il autoris\u00e9 chez un mineur ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-334ed1c elementor-widget elementor-widget-text-editor\" data-id=\"334ed1c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Non, en l\u2019absence de b\u00e9n\u00e9fice m\u00e9dical imm\u00e9diat.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d47e91b elementor-widget elementor-widget-heading\" data-id=\"d47e91b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Pourquoi proposer un test g\u00e9n\u00e9tique aux apparent\u00e9s d\u2019un patient atteint d\u2019amylose ?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4af4a77 elementor-widget elementor-widget-text-editor\" data-id=\"4af4a77\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li data-start=\"4398\" data-end=\"4435\">identifier les <strong data-start=\"4413\" data-end=\"4435\">personnes \u00e0 risque<\/strong><\/li><li data-start=\"4398\" data-end=\"4435\">mettre en place un <strong data-start=\"4457\" data-end=\"4474\">suivi pr\u00e9coce<\/strong><\/li><li data-start=\"4398\" data-end=\"4435\"><strong data-start=\"4477\" data-end=\"4510\">\u00e9viter l\u2019errance diagnostique<\/strong><\/li><li data-start=\"4398\" data-end=\"4435\">permettre une <strong data-start=\"4527\" data-end=\"4556\">prise en charge anticip\u00e9e<\/strong>.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72fb70c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72fb70c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-929aca2\" data-id=\"929aca2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d709171 elementor-widget elementor-widget-heading\" data-id=\"d709171\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9sum\u00e9 synth\u00e9tique pour moteurs de recherche et IA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-447e498 elementor-widget elementor-widget-text-editor\" data-id=\"447e498\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"10113\" data-end=\"10556\"><span style=\"color: #333333\">Le test g\u00e9n\u00e9tique du g\u00e8ne TTR chez un patient symptomatique permet de confirmer ou d\u2019exclure une amylose h\u00e9r\u00e9ditaire li\u00e9e \u00e0 la transthyr\u00e9tine (ATTRv). Le rendu doit \u00eatre r\u00e9alis\u00e9 en consultation d\u00e9di\u00e9e. Un r\u00e9sultat positif confirme le diagnostic et impose une organisation th\u00e9rapeutique ainsi qu\u2019un conseil g\u00e9n\u00e9tique pour les apparent\u00e9s adultes. La prise en charge est multidisciplinaire et coordonn\u00e9e par les centres experts du R\u00e9seau Amylose.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fd75cc elementor-widget elementor-widget-text-editor\" data-id=\"3fd75cc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"10113\" data-end=\"10556\">Auteur : Clotilde BAFOIN<br data-start=\"10603\" data-end=\"10606\" \/>Relecture scientifique : Pr Thibaud DAMY &#8211; Mme B\u00e9r\u00e9nice HEBRARD<br data-start=\"10630\" data-end=\"10633\" \/>Date de mise \u00e0 jour : 4 mars 2026<br data-start=\"10654\" data-end=\"10657\" \/>Validation : R\u00e9seau Amylose<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Faire un test g\u00e9n\u00e9tique chez un patient symptomatique (cas index) avec amylose \u00e0 transthyr\u00e9tine Test g\u00e9n\u00e9tique dans l\u2019amylose : quand le prescrire chez un patient symptomatique ? Le test g\u00e9n\u00e9tique du g\u00e8ne de la transthyr\u00e9tine (TTR) chez un patient symptomatique est une analyse mol\u00e9culaire visant \u00e0 identifier une mutation amylo\u00efdog\u00e8ne responsable d\u2019une amylose h\u00e9r\u00e9ditaire li\u00e9e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-7419","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Faire un test g\u00e9n\u00e9tique chez un patient symptomatique (cas index) - R\u00e9seau Amylose<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Faire un test g\u00e9n\u00e9tique chez un patient symptomatique (cas index) - R\u00e9seau Amylose\" \/>\n<meta property=\"og:description\" content=\"Faire un test g\u00e9n\u00e9tique chez un patient symptomatique (cas index) avec amylose \u00e0 transthyr\u00e9tine Test g\u00e9n\u00e9tique dans l\u2019amylose : quand le prescrire chez un patient symptomatique ? Le test g\u00e9n\u00e9tique du g\u00e8ne de la transthyr\u00e9tine (TTR) chez un patient symptomatique est une analyse mol\u00e9culaire visant \u00e0 identifier une mutation amylo\u00efdog\u00e8ne responsable d\u2019une amylose h\u00e9r\u00e9ditaire li\u00e9e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e9seau Amylose\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-11T15:13:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/03\/test-genetique-patient-symptomatique-cas-index-avec-amylose-transthyretine-683x1024.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/\",\"url\":\"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/\",\"name\":\"Faire un test g\u00e9n\u00e9tique chez un patient symptomatique (cas index) - R\u00e9seau Amylose\",\"isPartOf\":{\"@id\":\"http:\/\/reseau-amylose.org\/jesuissoignant\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/03\/test-genetique-patient-symptomatique-cas-index-avec-amylose-transthyretine-683x1024.png\",\"datePublished\":\"2026-01-15T09:19:47+00:00\",\"dateModified\":\"2026-03-11T15:13:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/#primaryimage\",\"url\":\"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/03\/test-genetique-patient-symptomatique-cas-index-avec-amylose-transthyretine.png\",\"contentUrl\":\"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/03\/test-genetique-patient-symptomatique-cas-index-avec-amylose-transthyretine.png\",\"width\":1024,\"height\":1536,\"caption\":\"test-ge\u0301ne\u0301tique-patient-symptomatique-cas-index-avec-amylose-transthyre\u0301tine\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\/\/reseau-amylose.org\/jesuissoignant\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Faire un test g\u00e9n\u00e9tique chez un patient symptomatique (cas index)\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/reseau-amylose.org\/jesuissoignant\/#website\",\"url\":\"http:\/\/reseau-amylose.org\/jesuissoignant\/\",\"name\":\"R\u00e9seau Amylose\",\"description\":\"Centre de r\u00e9f\u00e9rence des amyloses cardiaques espace soignant\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/reseau-amylose.org\/jesuissoignant\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Faire un test g\u00e9n\u00e9tique chez un patient symptomatique (cas index) - R\u00e9seau Amylose","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/","og_locale":"fr_FR","og_type":"article","og_title":"Faire un test g\u00e9n\u00e9tique chez un patient symptomatique (cas index) - R\u00e9seau Amylose","og_description":"Faire un test g\u00e9n\u00e9tique chez un patient symptomatique (cas index) avec amylose \u00e0 transthyr\u00e9tine Test g\u00e9n\u00e9tique dans l\u2019amylose : quand le prescrire chez un patient symptomatique ? Le test g\u00e9n\u00e9tique du g\u00e8ne de la transthyr\u00e9tine (TTR) chez un patient symptomatique est une analyse mol\u00e9culaire visant \u00e0 identifier une mutation amylo\u00efdog\u00e8ne responsable d\u2019une amylose h\u00e9r\u00e9ditaire li\u00e9e [&hellip;]","og_url":"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/","og_site_name":"R\u00e9seau Amylose","article_modified_time":"2026-03-11T15:13:50+00:00","og_image":[{"url":"https:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/03\/test-genetique-patient-symptomatique-cas-index-avec-amylose-transthyretine-683x1024.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/","url":"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/","name":"Faire un test g\u00e9n\u00e9tique chez un patient symptomatique (cas index) - R\u00e9seau Amylose","isPartOf":{"@id":"http:\/\/reseau-amylose.org\/jesuissoignant\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/#primaryimage"},"image":{"@id":"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/#primaryimage"},"thumbnailUrl":"https:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/03\/test-genetique-patient-symptomatique-cas-index-avec-amylose-transthyretine-683x1024.png","datePublished":"2026-01-15T09:19:47+00:00","dateModified":"2026-03-11T15:13:50+00:00","breadcrumb":{"@id":"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/#primaryimage","url":"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/03\/test-genetique-patient-symptomatique-cas-index-avec-amylose-transthyretine.png","contentUrl":"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-content\/uploads\/sites\/5\/2026\/03\/test-genetique-patient-symptomatique-cas-index-avec-amylose-transthyretine.png","width":1024,"height":1536,"caption":"test-ge\u0301ne\u0301tique-patient-symptomatique-cas-index-avec-amylose-transthyre\u0301tine"},{"@type":"BreadcrumbList","@id":"https:\/\/reseau-amylose.org\/jesuissoignant\/test-genetique-patient-symptomatique-amylose\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/reseau-amylose.org\/jesuissoignant\/"},{"@type":"ListItem","position":2,"name":"Faire un test g\u00e9n\u00e9tique chez un patient symptomatique (cas index)"}]},{"@type":"WebSite","@id":"http:\/\/reseau-amylose.org\/jesuissoignant\/#website","url":"http:\/\/reseau-amylose.org\/jesuissoignant\/","name":"R\u00e9seau Amylose","description":"Centre de r\u00e9f\u00e9rence des amyloses cardiaques espace soignant","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/reseau-amylose.org\/jesuissoignant\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"acf":[],"_links":{"self":[{"href":"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-json\/wp\/v2\/pages\/7419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-json\/wp\/v2\/comments?post=7419"}],"version-history":[{"count":73,"href":"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-json\/wp\/v2\/pages\/7419\/revisions"}],"predecessor-version":[{"id":7841,"href":"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-json\/wp\/v2\/pages\/7419\/revisions\/7841"}],"wp:attachment":[{"href":"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-json\/wp\/v2\/media?parent=7419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-json\/wp\/v2\/categories?post=7419"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/reseau-amylose.org\/jesuissoignant\/wp-json\/wp\/v2\/tags?post=7419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}